{"id":4392,"date":"2014-02-22T15:38:25","date_gmt":"2014-02-22T13:38:25","guid":{"rendered":"https:\/\/www.gesund24h.de\/blog\/?p=4392"},"modified":"2017-04-11T16:51:10","modified_gmt":"2017-04-11T14:51:10","slug":"autismus-gefangen-in-der-eigenen-welt","status":"publish","type":"post","link":"https:\/\/www.gesund24h.de\/blog\/allgemeines\/autismus-gefangen-in-der-eigenen-welt.html","title":{"rendered":"Autismus &#8211; gefangen in der eigenen Welt"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"left size-thumbnail wp-image-4395\" src=\"https:\/\/www.gesund24h.de\/blog\/wp-content\/uploads\/2014\/02\/junge-225x135.jpg\" alt=\"autistischer Junge\" width=\"225\" height=\"135\" \/>Wir Menschen sind soziale Wesen, wir leben in einer Gemeinschaft und definieren uns durch den Kontakt mit unseren Mitmenschen und unsere Stellung in der Gesellschaft. Ohne erf\u00fcllende Beziehungen mit anderen Leuten leben zu m\u00fcssen, erscheint den meisten Menschen als absolut furchtbarer Zustand. Tats\u00e4chlich ist aber genau das f\u00fcr viele Menschen Realit\u00e4t &#8211; und hier ist nicht die Rede von Strafgefangenen in Isolationshaft, sondern von Menschen, die unter einer autistischen St\u00f6rung leiden. Der Autismus ist somit unser heutiges Thema.<\/p>\n<p><!--more--><\/p>\n<h2>Was ist Autismus?<\/h2>\n<p>Autismus ist eine schwerwiegende Entwicklungsst\u00f6rung, die in unterschiedlichen Auspr\u00e4gungen und Formen vorliegen kann und vermutlich genetisch bedingt ist. Der Begriff kommt von dem griechischen Wort f\u00fcr \u201eSelbst\u201c (= \u201eautos\u201c)\u00a0 und meint, dass der Betroffene in sich selbst gefangen ist. Eine leichte autistische St\u00f6rung l\u00e4sst den Betroffenen zwar manchmal sonderbar wirken, schr\u00e4nkt ihn aber nur bedingt in seiner Lebensf\u00fchrung ein. Ist der Autismus allerdings ausgepr\u00e4gt, hat er \u00e4hnlich wie eine schwere Behinderung massive Auswirkungen auf das Leben des Patienten. Die Leistungseinschr\u00e4nkungen, die ein Betroffener erlebt, h\u00e4ngen aber vermutlich nicht mit einer zwangsl\u00e4ufigen Intelligenzminderung zusammen. Denn obwohl Autisten h\u00e4ufig unter Leistungsminderungen und Lernschw\u00e4chen leiden, liegt das doch weniger an ihrer Intelligenz, als an der \u201eanderen\u201c Wahrnehmung ihrer Umwelt.<\/p>\n<blockquote><p>Angaben \u00fcber die H\u00e4ufigkeit des Krankheitsbildes schwanken stark, was unter anderem auch daran liegt, dass die \u00dcberg\u00e4nge zwischen Normalit\u00e4t und Autismus h\u00e4ufig flie\u00dfend sind. Fest steht aber, dass deutlich mehr M\u00e4nner als Frauen von der St\u00f6rung betroffen sind.<\/p><\/blockquote>\n<p>Es gibt verschiedene Formen von Autismus, bei denen sich das Krankheitsbild jeweils unterscheidet. Eines haben aber alle Formen des Autismus gemeinsam: Menschen mit einer autistischen St\u00f6rung haben Schwierigkeiten, mit anderen zu kommunizieren. Von diesen Kommunikations-Problemen ist aber nicht die Sprache selbst betroffen, sondern vielmehr die komplette Wahrnehmung: Autisten k\u00f6nnen Gef\u00fchle, Stimmungen, Sinnbilder und vieles mehr nicht einordnen oder nachempfinden, daraus entstehen Missverst\u00e4ndnisse, die Kontakt- und Kommunikationsf\u00e4higkeit wird stark eingeschr\u00e4nkt. Dieses Fehlen grundlegender F\u00e4higkeiten kann so weit gehen, dass schwere Autisten \u00fcberhaupt nicht in der Lage sind, Kontakt mit anderen einzugehen, sondern ihre Mitmenschen als unbelebte Dinge betrachten.<\/p>\n<h2>Welche Formen von Autismus gibt es?<\/h2>\n<p>Wie bereits erw\u00e4hnt, unterscheidet man bei autistischen St\u00f6rungen mehrere unterschiedliche Formen mit unterschiedlicher Symptomatik. Die Weltgesundheitsorganisation (WHO) klassifiziert hier drei klar von einander abgrenzbare Formen: Den fr\u00fchkindlichen Autismus, den Asperger Autismus und den Atypischen Autismus.<\/p>\n<h3>Fr\u00fchkindlicher Autismus<\/h3>\n<p>Der fr\u00fchkindliche Autismus, auch Kanner-Syndrom genannt, ist die bekannteste autistische St\u00f6rung. Er tritt im Normalfall bereits vor dem dritten Lebensjahr auf und zeigt sich schon sehr fr\u00fch an dem fehlenden Interesse des Betroffenen an Sozialkontakten. Oft baut ein Mensch, der unter fr\u00fchkindlichem Autismus leidet, nicht einmal eine Beziehung zu seinen Eltern auf, sondern besch\u00e4ftigt sich lieber mit unbelebten Gegenst\u00e4nden. Ber\u00fchrungen und Zuneigungsbekundungen k\u00f6nnen h\u00e4ufig nicht richtig eingeordnet werden und werden deshalb vermieden oder abgelehnt. H\u00e4ufig kapseln sich Kanner Autisten deshalb fast vollst\u00e4ndig von anderen Menschen ab und ziehen sich in die Isolation ihrer eigenen Ding-Welt zur\u00fcck. Ver\u00e4nderungen sind f\u00fcr einen solchen Autisten nur sehr schwer zu verkraften, schon ein Umstellen der M\u00f6bel kann eine Angstattacke ausl\u00f6sen. Die Sprachentwicklung von Kanner Autisten ist oft auff\u00e4llig: Die Sprachmelodie ist monoton und frei von bildlichen oder abstrakten Elementen, f\u00fcr sinnbildliche \u00dcbertragungen, Ironie und \u00e4hnliches hat der Betroffene kein Verst\u00e4ndnis, stattdessen wird Sprache wortw\u00f6rtlich wahrgenommen und praktiziert. Etwa ein Drittel der Betroffenen f\u00fchlt so wenig Notwendigkeit zur Kommunikation, dass es niemals die Fertigkeiten zur lautsprachlichen Kommunikation erwirbt. Menschen, die an einem starken Kanner Autismus leiden, sind nicht in der Lage sich in die Gesellschaft einzuf\u00fcgen und ben\u00f6tigen h\u00e4ufig eine lebenslange Begleitung und Unterst\u00fctzung, um ihr Leben innerhalb fester Rahmenbedingungen meistern zu k\u00f6nnen.<\/p>\n<h3>Asperger Autismus<\/h3>\n<p>Im Gegensatz zu Patienten mit Kanner-Syndrom, ziehen sich Menschen, die am Asperger-Syndrom leiden, nicht in sich selbst zur\u00fcck, sondern suchen den Kontakt zu anderen. Der starke Wunsch nach Sozialkontakten ist vorhanden, die Umsetzung gestaltet sich allerdings wegen der bereits genannten f\u00fcr jede Form von Autismus typischen Kommunikationsschwierigkeiten problematisch. Da ein Asperger Autist sich nicht oder nur sehr schwer in anderen Hineinf\u00fchlen kann, sind seine Versuche, soziale Kontakte aufzubauen oft unbeholfen und selten erfolgversprechend. Durch fehlendes Distanzempfinden \u00fcberfordern Asperger Autisten ihre Mitmenschen oft. Zum Teil ist zus\u00e4tzlich die Impulskontrolle eingeschr\u00e4nkt, wodurch es zu unkontrollierten Aggressionen, aber auch zu \u00fcberschw\u00e4nglichen Liebesbekundungen kommen kann. Dazu kommt h\u00e4ufig eine Dyspraxie, was bedeutet, dass der Betroffene handwerklich und praktisch h\u00e4ufig sehr ungeschickt ist und vorhandene Handlungsentw\u00fcrfe oft nicht in die Tat umsetzen kann. Logische und abstrakte F\u00e4higkeiten sind bei dieser Form des Autismus allerdings normalerweise gut ausgepr\u00e4gt, Interessen und Hobbys werden nicht selten mit einer erstaunlichen Leistungsf\u00e4higkeit verfolgt, Wissen zu einzelnen Fachbereichen beinahe lexikalisch angesammelt und wiedergegeben. Asperger Autisten\u00a0 k\u00f6nnen so ein weitgehend normales Leben f\u00fchren, auch wenn die soziale Integration h\u00e4ufig ein Leben lang Probleme bereitet.<\/p>\n<h3>Atypischer Autismus<\/h3>\n<p>Der Atypische Authismus ist eine Unterform, die gro\u00dfe \u00c4hnlichkeit mit dem Kanner-Syndrom aufweist, allerdings nicht alle Diagnose-Kriterien erf\u00fcllt. Damit ist sie so etwas wie ein Sammelbegriff f\u00fcr untypische oder unvollst\u00e4ndige Formen von Autismus.<\/p>\n<h2>Autismus und Hochbegabung<\/h2>\n<p>Sp\u00e4testens seit dem Film \u201eRain Man\u201c ist das Klischee von Autismus h\u00e4ufig mit dem Ph\u00e4nomen der Hochbegabung gekoppelt \u2013 dies entspricht allerdings nur in wenigen F\u00e4llen der Realit\u00e4t. Normale Autisten mit dem Kanner-Syndrom sind nicht h\u00e4ufiger von einer Hochbegabung betroffen, als andere Menschen auch. Bei High Functioning Autismus, einer Auspr\u00e4gungsform, bei der es zu keinerlei Intelligenzminderung kommt, wirkt der Betroffene allerdings gelegentlich \u201ekl\u00fcger\u201c, weil er sich nicht von zwischenmenschlichen Regungen ablenken l\u00e4sst, sondern sich beharrlich dem Sachverhalt widmet, der sein Interesse weckt. Zwar ist eine Hochbegabung auch bei einem Autisten nicht ausgeschlossen, allerdings kann er durch seine krankheitsbedingte Einschr\u00e4nkung nicht immer auf seine Begabung zur\u00fcckgreifen. Inselbegabungen sind hier die h\u00e4ufigste Form: Der Betroffene zentriert seine Talente auf lediglich einen Bereich seines Lebens, in Bezug auf den Rest ist er nicht selten hilflos \u2013 dieses Ph\u00e4nomen nennt man Savant-Syndrom.<\/p>\n<p>Bei dem Asperger Autismus kommt man dem Klischee des klugen Autisten allerdings schon n\u00e4her, denn bei den Betroffenen dieser Autismus-Form liegen normalerweise keine Intelligenzminderungen vor, stattdessen ist die Intelligenz normal bis hoch ausgepr\u00e4gt. Da bei diesem Krankheitsbild die F\u00e4higkeit, abstrakt und logisch zu denken gut ausgebildet ist, entwickeln Betroffene h\u00e4ufig ein verst\u00e4rktes Interesse f\u00fcr den mathematischen oder naturwissenschaftlichen Bereich und zeigen hier au\u00dfergew\u00f6hnliche Begabung und Leistungsf\u00e4higkeit. Durch das andere Denken und Wahrnehmen von Asperger Autisten gehen manche Forscher auch davon aus, dass bei diesem Krankheitsbild ein erh\u00f6htes Ma\u00df an Kreativit\u00e4t vorhanden ist, hier gibt es allerdings noch keine beweiskr\u00e4ftigen Studien.<\/p>\n<h2>Autismus und die Prognosen f\u00fcr die Zukunft<\/h2>\n<p>Da Autismus vermutlich genetisch bedingt ist, ist er nicht heilbar und es gibt auch keine wirkungsvolle Therapie f\u00fcr die Krankheit \u2013 was allerdings nicht hei\u00dft, dass man der St\u00f6rung auf Gedeih und Verderb ausgeliefert w\u00e4re. Mit zunehmendem Bekanntheitsgrad des Krankheitsbildes werden auch immer neue Hilfsmodelle entwickelt. Wichtig ist hier, dass Autismus nicht einseitig behandelt werden kann: Um die Symptomatik bessern zu k\u00f6nnen, m\u00fcssen mehrere Hilfsinstanzen in einem eng verwobenen System zusammenarbeiten. Das Hilfesystem sollte schon bei der fr\u00fchkindlichen F\u00f6rderung beginnen, auch soziale Trainingsma\u00dfnahmen und sozialp\u00e4dagogische Begleitung sind sinnvoll, um Autisten die f\u00fcr die Lebensbew\u00e4ltigung notwendigen Fertigkeiten zu vermitteln. Und auch Eltern und andere nahe Verwandte sollten nicht z\u00f6gern, Hilfe aufzusuchen und anzunehmen, um die Belastung durch ein autistisches Kind meistern zu k\u00f6nnen. Dann ist auch f\u00fcr einen Autisten ein weitgehend normales Leben m\u00f6glich. Ein Ressourcen-orientiertes Herangehen an die Krankheit erm\u00f6glicht es einem Betroffenen auch, seine teilweise au\u00dfergew\u00f6hnlichen Begabungen zu seinem Vorteil zu nutzen. Wichtig ist auf jeden Fall, dass Autismus als solcher entstigmatisiert wird, um den Betroffenen ein Leben innerhalb der Gesellschaft zu erm\u00f6glichen.<\/p>\n<p>Weitere Informationen finden Sie unter: <a href=\"http:\/\/www.autismus.de\" target=\"_blank\">Autismus Deutschland e.V.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Viele Gr\u00fc\u00dfe<br \/>\nPetra Fischer<br \/>\nGesund24h<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir Menschen sind soziale Wesen, wir leben in einer Gemeinschaft und definieren uns durch den Kontakt mit unseren Mitmenschen und unsere Stellung in der Gesellschaft. Ohne erf\u00fcllende Beziehungen mit anderen Leuten leben zu m\u00fcssen, erscheint den meisten Menschen als absolut<\/p>\n","protected":false},"author":1,"featured_media":4395,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemeines"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/posts\/4392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/comments?post=4392"}],"version-history":[{"count":0,"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/posts\/4392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/media\/4395"}],"wp:attachment":[{"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/media?parent=4392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/categories?post=4392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gesund24h.de\/blog\/wp-json\/wp\/v2\/tags?post=4392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}